{"id":140126,"date":"2025-07-31T05:58:35","date_gmt":"2025-07-31T03:58:35","guid":{"rendered":"https:\/\/www.budream.com\/shop\/sweet-seeds-nyc-diesel-cbd-fem-anciennement-ice-cool-cbd-fem\/"},"modified":"2025-12-12T14:02:01","modified_gmt":"2025-12-12T12:02:01","slug":"sweet-seeds-nyc-diesel-cbd-fem-anciennement-ice-cool-cbd-fem","status":"publish","type":"product","link":"https:\/\/www.budream.com\/fr\/shop\/sweet-seeds-nyc-diesel-cbd-fem-anciennement-ice-cool-cbd-fem\/","title":{"rendered":"SWEET SEEDS &#8211; NYC DIESEL CBD\u00ae FEM (anciennement ICE COOL CBD\u00ae FEM)"},"content":{"rendered":"<div style=\"text-align: justify\">Disponible jusqu&rsquo;\u00e0 \u00e9puisement des stocks<\/p>\n<p>Version riche en CBD de l&rsquo;une des meilleures g\u00e9n\u00e9tiques de notre catalogue, notre bien-aim\u00e9e NYC Diesel&reg; (SWS06). Deux lign\u00e9es g\u00e9n\u00e9tiques de la famille Diesel, notre NYC Diesel&reg; et un clone \u00ab\u00a0\u00e9lite\u00a0\u00bb s\u00e9lectionn\u00e9 \u00e0 partir d&rsquo;anc\u00eatres Diesel riches en CBD, fusionnent dans cette vari\u00e9t\u00e9.<\/p><\/div>\n<p><\/p>\n<h2><strong>Caract\u00e9ristiques NYC Diesel CBD Fem (SWS69) Sweet Seeds :<\/strong><\/h2>\n<ul style=\"list-style-type: disc\">\n<li><strong>Genre :<\/strong> Hybride F\u00e9minis\u00e9e<\/li>\n<li><strong>G\u00e9n\u00e9tique :<\/strong> NYC Diesel x clone Elite riche en CBD<\/li>\n<li><strong>Composition :<\/strong> 40% Indica \/ 60% Sativa<\/li>\n<li><strong>Jours :<\/strong> 56-63<\/li>\n<\/ul>\n<p><\/p>\n<div style=\"text-align: justify\"><span style=\"font-size: 11pt\"><em><strong>ATTENTION :<\/strong> Les graines de chanvre sont exclues de la notion l\u00e9gale de Cannabis, ce qui signifie qu&rsquo;elles ne doivent pas \u00eatre consid\u00e9r\u00e9es comme une substance stup\u00e9fiante (L. 412 de 1974, art. 1, virgule 1, lett. B ; Convention unique sur les stup\u00e9fiants de New York de 1961 et tableau II du d\u00e9cret minist\u00e9riel 27\/7\/1992). En Italie, la culture du chanvre est interdite (articles 28 et 73 du d\u00e9cret pr\u00e9sidentiel 309\/90), sauf autorisation sp\u00e9ciale (article 17 du d\u00e9cret pr\u00e9sidentiel 309\/90). En l&rsquo;absence d&rsquo;autorisation, les semences ne peuvent \u00eatre utilis\u00e9es qu&rsquo;\u00e0 d&rsquo;autres fins (zootechniques, de collection, etc.). Les semences sont vendues sous r\u00e9serve qu&rsquo;elles ne soient pas utilis\u00e9es par des tiers en contradiction avec la loi.<\/em><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Disponible jusqu&rsquo;\u00e0 \u00e9puisement des stocks Version riche en CBD de l&rsquo;une des meilleures g\u00e9n\u00e9tiques de notre catalogue, notre bien-aim\u00e9e NYC<\/p>\n","protected":false},"featured_media":140116,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[7951],"product_tag":[],"class_list":{"0":"post-140126","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-magasin-de-graines","8":"first","9":"instock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/product\/140126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/comments?post=140126"}],"version-history":[{"count":0,"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/product\/140126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/media\/140116"}],"wp:attachment":[{"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/media?parent=140126"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/product_brand?post=140126"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/product_cat?post=140126"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.budream.com\/fr\/wp-json\/wp\/v2\/product_tag?post=140126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}